{"id":2693,"date":"2018-10-08T14:33:22","date_gmt":"2018-10-08T17:33:22","guid":{"rendered":"https:\/\/caminhodafe.com.br\/ptbr\/?page_id=2693"},"modified":"2026-05-21T10:36:10","modified_gmt":"2026-05-21T13:36:10","slug":"prestacao-de-contas-por-cidades","status":"publish","type":"page","link":"https:\/\/caminhodafe.com.br\/ptbr\/prestacao-de-contas-por-cidades\/","title":{"rendered":"Cidades parceiras (Documentos e Presta\u00e7\u00e3o de Contas)"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h4>Nesta p\u00e1gina voc\u00ea encontrar\u00e1 as documenta\u00e7\u00f5es referentes \u00e0s parcerias com as cidades que fazem parte do Caminho da F\u00e9, bem como as presta\u00e7\u00f5es de contas.<\/h4>\n<h4>Para acessar, \u00e9 so clicar no nome da cidade.<\/h4>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #000080;\"><strong>CIDADES<\/strong><\/span><\/h3>\n<p>&nbsp;<\/p>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/aguai-prestacao-de-contas\/\">Agua\u00ed<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/aguas-da-prata-prestacao-de-contas\/\">\u00c1guas da Prata<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/andradas-prestacao-de-contas\/\">Andradas<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/aparecida-prestacao-de-contas\/\">Aparecida<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/arceburgo-prestacao-de-contas\/\">Arceburgo<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/boa-esperanca-do-sul-prestacao-de-contas\/\">Boa Esperan\u00e7a do Sul<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/bom-repouso-prestacao-de-contas\/\">Bom Repouso<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/borborema-prestacao-de-contas\/\">Borborema<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/borda-prestacao-de-contas\/\">Borda da Mata<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/botelhos-prestacao-de-contas\/\">Botelhos<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/bueno-prestacao-de-contas\/\">Bueno Brand\u00e3o<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/brazopolis-prestacao-de-contas\/\">Braz\u00f3polis<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/caconde-prestacao-de-contas\/\">Caconde<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/caldas-prestacao-de-contas\/\">Caldas<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/campestre-prestacao-de-contas\/\">Campestre<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/campos-prestacao-de-contas\/\">Campos do Jord\u00e3o<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/casa-branca-prestacao-de-contas\/\">Casa Branca<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/cedral-prestacao-de-contas\/\">Cedral<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/consolacao-prestacao-de-contas\/\">Consola\u00e7\u00e3o<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/cravinhos-prestacao-de-contas\/\">Cravinhos<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/descalvado-prestacao-de-contas\/\">Descalvado<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/divinolandia-prestacao-de-contas-2\/\">Divinol\u00e2ndia<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/dumont\/\">Dumont<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/pinhal\/\">Esp\u00edrito Santo do Pinhal<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/estiva\/\">Estiva<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/estiva-gerbi-prestacao-de-contas\/\">Estiva Gerbi<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/franca\/\">Franca<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/gaviao\/\">Gavi\u00e3o Peixoto<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/guaratingueta-prestacao-de-contas\/\">Guaratinguet\u00e1<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/guaxupe-prestacao-de-contas\/\">Guaxup\u00e9<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/ibira-prestacao-de-contas\/\">Ibir\u00e1 <\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/ibitinga-prestacao-de-contas\/\">Ibitinga<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/inconfidentes-prestacao-de-contas\/\">Inconfidentes<\/a><\/h4>\n<h4>Itamogi<\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/itapolis-prestacao-de-contas\/\">It\u00e1polis<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/itirapua-prestacao-de-contas\/\">Itirapu\u00e3<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/itobi-prestacao-de-contas\/\">Itobi<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/leme-prestacao-de-contas\/\">Leme<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/jaboticabal-prestacao-de-contas\/\">Jaboticabal<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/mococa-prestacao-de-contas\/\">Mococa<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/monte-santo-de-minas-prestacao-de-contas\/\">Monte Santo de Minas<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/monte-siao-prestacao-de-contas\/\">Monte Si\u00e3o<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/nova-europa-prestacao-de-contas\/\">Nova Europa<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/novo-horizonte-prestacao-de-contas\/\">Novo Horizonte<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/ouro-fino-prestacao-de-contas\/\">Ouro Fino<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/paraisopolis-prestacao-de-contas\/\">Parais\u00f3polis<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/patrocinio-prestacao-de-contas\/\">Patroc\u00ednio Paulista<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/pindamonhangaba-prestacao-de-contas\/\">Pindamonhangaba<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/porto-ferreira-prestacao-de-contas\/\">Porto Ferreira<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/potim-prestacao-de-contas\/\">Potim<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/potirendaba-prestacao-de-contas-2\/\">Potirendaba<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/ribeirao-bonito-prestacao-de-contas\/\">Ribeir\u00e3o Bonito<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/santa-rita-de-caldas-prestacao-de-contas\/\">Santa Rita de Caldas<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/passa-quatro-prestacao-de-contas\/\">Santa Rita do Passa Quatro<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/santa-rosa-do-viterbo-prestacao-de-contas\/\">Santa Rosa do Viterbo<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/santo-antonio-jardim-prestacao-de-contas\/\">Santo Ant\u00f4nio do Jardim<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/sao-carlos-prestacao-de-contas\/\">S\u00e3o Carlos<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/sao-joao-da-boa-vista-prestacao-de-contas\/\">S\u00e3o Jo\u00e3o da Boa Vista<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/sao-jose-do-rio-pardo-prestacao-de-contas\/\">S\u00e3o Jos\u00e9 do Rio Pardo<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/sao-jose-do-rio-preto-prestacao-de-contas\/\">S\u00e3o Jos\u00e9 do Rio Preto<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/sao-sebastiao-da-grama-prestacao-de-contas\/\">S\u00e3o Sebasti\u00e3o da Grama<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/sao-sebastiao-do-paraiso-prestacao-de-contas\/\">S\u00e3o Sebasti\u00e3o do Para\u00edso<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/sao-simao-prestacao-de-contas\/\">S\u00e3o Sim\u00e3o<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/sao-tomas-de-aquino-prestacao-de-contas\/\">S\u00e3o Tom\u00e1s de Aquino<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/sertaozinho-prestacao-de-contas\/\">Sert\u00e3ozinho<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/tabatinga-prestacao-de-contas\/\">Tabatinga<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/tambau-prestacao-de-contas\/\">Tamba\u00fa<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/tapiratiba-prestacao-de-contas\/\">Tapiratiba<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/tocos-do-moji-prestacao-de-contas\/\">Tocos do Moji<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/trabiju-prestacao-de-contas\/\">Trabiju<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/urupes-prestacao-de-contas\/\">Urup\u00eas<\/a><\/h4>\n<h4><a href=\"https:\/\/caminhodafe.com.br\/ptbr\/vargem-grande-do-sul-prestacao-de-contas\/\">Vargem Grande do Sul<\/a><\/h4>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Nesta p\u00e1gina voc\u00ea encontrar\u00e1 as documenta\u00e7\u00f5es referentes \u00e0s parcerias com as cidades que fazem parte do Caminho da F\u00e9, bem como as presta\u00e7\u00f5es de contas. Para acessar, \u00e9 so clicar no nome da cidade. &nbsp; CIDADES &nbsp; Agua\u00ed \u00c1guas da Prata Andradas Aparecida Arceburgo Boa Esperan\u00e7a do Sul Bom Repouso Borborema Borda da Mata Botelhos Bueno Brand\u00e3o Braz\u00f3polis Caconde Caldas Campestre Campos do Jord\u00e3o Casa Branca Cedral Consola\u00e7\u00e3o Cravinhos Descalvado Divinol\u00e2ndia Dumont Esp\u00edrito Santo do Pinhal Estiva Estiva Gerbi Franca Gavi\u00e3o Peixoto Guaratinguet\u00e1 Guaxup\u00e9 Ibir\u00e1 Ibitinga Inconfidentes Itamogi It\u00e1polis Itirapu\u00e3 Itobi Leme Jaboticabal Mococa Monte Santo de Minas Monte Si\u00e3o Nova Europa Novo Horizonte Ouro Fino Parais\u00f3polis Patroc\u00ednio Paulista Pindamonhangaba Porto Ferreira Potim Potirendaba Ribeir\u00e3o Bonito Santa Rita de Caldas Santa Rita do Passa Quatro Santa Rosa do Viterbo Santo Ant\u00f4nio do Jardim S\u00e3o Carlos S\u00e3o Jo\u00e3o da Boa Vista S\u00e3o Jos\u00e9 do Rio Pardo S\u00e3o Jos\u00e9 do Rio Preto S\u00e3o Sebasti\u00e3o da Grama S\u00e3o Sebasti\u00e3o do Para\u00edso S\u00e3o Sim\u00e3o S\u00e3o Tom\u00e1s de Aquino Sert\u00e3ozinho Tabatinga Tamba\u00fa Tapiratiba Tocos do Moji Trabiju Urup\u00eas Vargem Grande do Sul [\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"iawp_total_views":1,"footnotes":""},"class_list":["post-2693","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/caminhodafe.com.br\/ptbr\/wp-json\/wp\/v2\/pages\/2693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/caminhodafe.com.br\/ptbr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/caminhodafe.com.br\/ptbr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/caminhodafe.com.br\/ptbr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/caminhodafe.com.br\/ptbr\/wp-json\/wp\/v2\/comments?post=2693"}],"version-history":[{"count":4,"href":"https:\/\/caminhodafe.com.br\/ptbr\/wp-json\/wp\/v2\/pages\/2693\/revisions"}],"predecessor-version":[{"id":12078,"href":"https:\/\/caminhodafe.com.br\/ptbr\/wp-json\/wp\/v2\/pages\/2693\/revisions\/12078"}],"wp:attachment":[{"href":"https:\/\/caminhodafe.com.br\/ptbr\/wp-json\/wp\/v2\/media?parent=2693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}